{"id":1682,"date":"2021-01-06T08:00:38","date_gmt":"2021-01-06T07:00:38","guid":{"rendered":"https:\/\/www.brulafine.com\/magazine\/?p=1682"},"modified":"2021-01-04T14:15:57","modified_gmt":"2021-01-04T13:15:57","slug":"recette-brioche-des-rois","status":"publish","type":"post","link":"https:\/\/www.brulafine.com\/magazine\/recette-brioche-des-rois\/","title":{"rendered":"Recette : Brioche des rois"},"content":{"rendered":"<p style=\"text-align: center;\">Pr\u00e9paration : 2 jours (temps de <a href=\"https:\/\/www.brulafine.com\/magazine\/le-manque-de-sommeil-fait-il-grossir\/\" data-internallinksmanager029f6b8e52c=\"117\" title=\"Le manque de sommeil fait-il grossir ?\">repos<\/a> compris)<br \/>\nCuisson :\u00a0 20 minutes<br \/>\nPortions : 4 personnes<\/p>\n<h2>Ingr\u00e9dients<\/h2>\n<h3>Pour la brioche<\/h3>\n<p><img class=\" wp-image-1683 alignleft\" src=\"https:\/\/www.brulafine.com\/magazine\/wp-content\/uploads\/2021\/01\/couronne-des-rois-300x282.jpg\" alt=\"brioche des rois\" width=\"209\" height=\"197\" srcset=\"https:\/\/www.brulafine.com\/magazine\/wp-content\/uploads\/2021\/01\/couronne-des-rois-300x282.jpg 300w, https:\/\/www.brulafine.com\/magazine\/wp-content\/uploads\/2021\/01\/couronne-des-rois-768x721.jpg 768w, https:\/\/www.brulafine.com\/magazine\/wp-content\/uploads\/2021\/01\/couronne-des-rois-512x481.jpg 512w, https:\/\/www.brulafine.com\/magazine\/wp-content\/uploads\/2021\/01\/couronne-des-rois.jpg 885w\" sizes=\"(max-width: 209px) 100vw, 209px\" \/>280 g de farine T45<br \/>\n10 g de levure fra\u00eeche\u00a0de boulanger<br \/>\n80 ml de lait<br \/>\n1 \u0153uf<br \/>\n4 cuill\u00e8res \u00e0 <a href=\"https:\/\/www.brulafine.com\/magazine\/se-nourrir-uniquement-de-soupe-bonne-ou-mauvaise-idee\/\" data-internallinksmanager029f6b8e52c=\"39\" title=\"Se nourrir uniquement de soupe : bonne ou mauvaise id\u00e9e ?\">soupe<\/a> de <a href=\"https:\/\/www.brulafine.com\/magazine\/differencier-le-bon-sucre-du-mauvais\/\" data-internallinksmanager029f6b8e52c=\"60\" title=\"Diff\u00e9rencier le bon sucre du mauvais\">sucre<\/a><br \/>\n1\/2 cuill\u00e8re \u00e0 <a href=\"https:\/\/www.brulafine.com\/magazine\/arreter-le-sucre-dans-le-cafe-cest-possible\/\" data-internallinksmanager029f6b8e52c=\"44\" title=\"Arr\u00eater le sucre dans le caf\u00e9 c\u2019est possible\u00a0!\">caf\u00e9<\/a> de sel<br \/>\n1 cuill\u00e8re \u00e0 soupe d&rsquo;eau de fleur d&rsquo;oranger<br \/>\n70 g de beurre mou coup\u00e9 en d\u00e9s<\/p>\n<h3>Pour la d\u00e9coration<\/h3>\n<p>2 cuill\u00e8res \u00e0 soupe de lait<br \/>\nsucre en grains<br \/>\n1 f\u00e8ve<\/p>\n<h2>Pr\u00e9paration<\/h2>\n<h3>La veille au soir<\/h3>\n<p>1. \u00c9miettez la levure de boulanger dans le lait ti\u00e8de et laissez reposer une dizaine de minutes.<\/p>\n<p>2. M\u00e9langez tous les ingr\u00e9dients sauf le beurre (en \u00e9vitant que le sel et la levure entrent en contact) et p\u00e9trissez jusqu\u2019\u00e0 obtenir une consistance souple et \u00e9lastique. Une fois cette consistance obtenue, ajoutez le beurre et p\u00e9trissez \u00e0 nouveau jusqu\u2019\u00e0 ce qu\u2019il soit bien incorpor\u00e9 \u00e0 la p\u00e2te.<\/p>\n<p>3. Mettez votre p\u00e2ton dans un saladier et laissez reposer environ une heure \u00e0 temp\u00e9rature ambiante.<\/p>\n<p>4. Filmez le saladier et mettez le tout au r\u00e9frig\u00e9rateur pour la nuit.<\/p>\n<h3>Le lendemain<\/h3>\n<p>1.\u00a0 P\u00e9trissez votre p\u00e2ton quelques minutes et ajoutez la f\u00e8ve. Laissez reposer 5 minutes puis faites un trou au milieu et \u00e9tirez-le de fa\u00e7on \u00e0 former une couronne.<\/p>\n<p>2. D\u00e9posez cette couronne sur une plaque de cuisson recouverte de papier sulfuris\u00e9 et laissez \u00e0 nouveau lever pendant 1h30 &#8211; 2h.<\/p>\n<p>3. Badigeonnez voter couronne de lait avec un pinceau, puis saupoudrez le sucre perl\u00e9.<\/p>\n<p>4. Enfournez dans un four non pr\u00e9chauff\u00e9, thermostat 150\u00b0C, chaleur tournante pour une vingtaine de minutes.<\/p>\n<p>5. Laissez refroidir sur grille.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pr\u00e9paration : 2 jours (temps de repos compris) Cuisson :\u00a0 20 minutes Portions : 4 personnes Ingr\u00e9dients Pour la brioche&#8230;<\/p>\n","protected":false},"author":1,"featured_media":1666,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[45],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.brulafine.com\/magazine\/wp-json\/wp\/v2\/posts\/1682"}],"collection":[{"href":"https:\/\/www.brulafine.com\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.brulafine.com\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.brulafine.com\/magazine\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.brulafine.com\/magazine\/wp-json\/wp\/v2\/comments?post=1682"}],"version-history":[{"count":2,"href":"https:\/\/www.brulafine.com\/magazine\/wp-json\/wp\/v2\/posts\/1682\/revisions"}],"predecessor-version":[{"id":1685,"href":"https:\/\/www.brulafine.com\/magazine\/wp-json\/wp\/v2\/posts\/1682\/revisions\/1685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.brulafine.com\/magazine\/wp-json\/wp\/v2\/media\/1666"}],"wp:attachment":[{"href":"https:\/\/www.brulafine.com\/magazine\/wp-json\/wp\/v2\/media?parent=1682"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.brulafine.com\/magazine\/wp-json\/wp\/v2\/categories?post=1682"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.brulafine.com\/magazine\/wp-json\/wp\/v2\/tags?post=1682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}